{"id":15980,"date":"2024-06-25T11:33:17","date_gmt":"2024-06-25T11:33:17","guid":{"rendered":"https:\/\/stage.diamondtours.pt\/?page_id=15980"},"modified":"2024-07-02T13:47:07","modified_gmt":"2024-07-02T13:47:07","slug":"galeria-grutas","status":"publish","type":"page","link":"https:\/\/diamondtours.pt\/en\/galeria-grutas\/","title":{"rendered":"Caves Gallery"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"15980\" class=\"elementor elementor-15980\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8e666d e-grid e-con-full e-con e-parent\" data-id=\"e8e666d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-613045b wd-width-100 elementor-widget elementor-widget-wd_images_gallery\" data-id=\"613045b\" data-element_type=\"widget\" data-widget_type=\"wd_images_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-images-gallery photoswipe-images\" style=\"--wd-align-items:center; --wd-justify-content:center;\">\n\t\t\t\t\t\t<div class=\"wd-masonry wd-grid-f-col\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:1;--wd-gap-lg:6px;\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"1\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg\"alt=\"5bc4642824758387571456\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/636a213cada7f012666915-scaled.jpg\"data-width=\"2560\" data-height=\"1920\" data-index=\"2\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/636a213cada7f012666915-1067x800.jpg\"alt=\"636a213cada7f012666915\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642568443009930655.jpg\"data-width=\"1920\" data-height=\"1200\" data-index=\"3\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642568443009930655-1280x800.jpg\"alt=\"5bc4642568443009930655\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642467147214865706.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"4\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642467147214865706-1067x800.jpg\"alt=\"5bc4642467147214865706\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642285285625730600.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"5\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642285285625730600-1300x731.jpg\"alt=\"5bc4642285285625730600\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464359588e141678117-scaled.jpg\"data-width=\"2560\" data-height=\"1600\" data-index=\"6\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464359588e141678117-1280x800.jpg\"alt=\"5bc464359588e141678117\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464342519c669282517.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"7\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464342519c669282517-1067x800.jpg\"alt=\"5bc464342519c669282517\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464295064d971931498.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"8\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464295064d971931498-1067x800.jpg\"alt=\"5bc464295064d971931498\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464278231d837608793.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"9\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464278231d837608793-600x800.jpg\"alt=\"5bc464278231d837608793\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46434693f3693220836.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"10\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46434693f3693220836-1067x800.jpg\"alt=\"5bc46434693f3693220836\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46433354a7724259780-1.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"11\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46433354a7724259780-1-1067x800.jpg\"alt=\"5bc46433354a7724259780\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46426482b4752541867-1.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"12\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46426482b4752541867-1-600x800.jpg\"alt=\"5bc46426482b4752541867\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46424231fe560663867-1.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"13\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46424231fe560663867-1-1067x800.jpg\"alt=\"5bc46424231fe560663867\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4648600b9a098219987.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"14\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4648600b9a098219987-1300x731.jpg\"alt=\"5bc4648600b9a098219987\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4643559c55371487658.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"15\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4643559c55371487658-1067x800.jpg\"alt=\"5bc4643559c55371487658\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4643389b83014799671.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"16\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4643389b83014799671-1067x800.jpg\"alt=\"5bc4643389b83014799671\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4643065e39655666344.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"17\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4643065e39655666344-1300x731.jpg\"alt=\"5bc4643065e39655666344\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642331f93522036681.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"18\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642331f93522036681-1300x731.jpg\"alt=\"5bc4642331f93522036681\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642243e20420934615.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"19\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642243e20420934615-1300x731.jpg\"alt=\"5bc4642243e20420934615\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464350c6ea753230926.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"20\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464350c6ea753230926-1067x800.jpg\"alt=\"5bc464350c6ea753230926\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464328d33a371339176.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"21\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464328d33a371339176-1300x731.jpg\"alt=\"5bc464328d33a371339176\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464324cd36271180568.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"22\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464324cd36271180568-1300x731.jpg\"alt=\"5bc464324cd36271180568\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464315c19b433900312.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"23\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464315c19b433900312-1300x731.jpg\"alt=\"5bc464315c19b433900312\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464310f1cc502977812.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"24\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464310f1cc502977812-1300x731.jpg\"alt=\"5bc464310f1cc502977812\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464301bc4a625867815.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"25\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464301bc4a625867815-1300x731.jpg\"alt=\"5bc464301bc4a625867815\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464275a529997816653.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"26\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464275a529997816653-600x800.jpg\"alt=\"5bc464275a529997816653\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464260f65b612905297.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"27\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464260f65b612905297-600x800.jpg\"alt=\"5bc464260f65b612905297\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464250cb50351674193-2.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"28\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464250cb50351674193-2-1067x800.jpg\"alt=\"5bc464250cb50351674193\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464237bf4b098259537.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"29\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464237bf4b098259537-1300x731.jpg\"alt=\"5bc464237bf4b098259537\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464213f3ad761528647.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"30\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464213f3ad761528647-1300x731.jpg\"alt=\"5bc464213f3ad761528647\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464209eafb559129270.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"31\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc464209eafb559129270-1300x731.jpg\"alt=\"5bc464209eafb559129270\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46434b80db806515926.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"32\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46434b80db806515926-1067x800.jpg\"alt=\"5bc46434b80db806515926\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46433c6e25873786459.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"33\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46433c6e25873786459-1067x800.jpg\"alt=\"5bc46433c6e25873786459\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46432e620d984722504.jpg\"data-width=\"1200\" data-height=\"900\" data-index=\"34\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46432e620d984722504-1067x800.jpg\"alt=\"5bc46432e620d984722504\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46431e8540823601719.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"35\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46431e8540823601719-1300x731.jpg\"alt=\"5bc46431e8540823601719\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46431aaf04677801431.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"36\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46431aaf04677801431-1300x731.jpg\"alt=\"5bc46431aaf04677801431\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46430b28f9685620360.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"37\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46430b28f9685620360-1300x731.jpg\"alt=\"5bc46430b28f9685620360\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46429e26de506847511.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"38\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46429e26de506847511-600x800.jpg\"alt=\"5bc46429e26de506847511\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46428b7722225454128.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"39\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46428b7722225454128-600x800.jpg\"alt=\"5bc46428b7722225454128\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46428b2c7a650729839.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"40\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46428b2c7a650729839-1067x800.jpg\"alt=\"5bc46428b2c7a650729839\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46427f03a1359723114.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"41\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46427f03a1359723114-600x800.jpg\"alt=\"5bc46427f03a1359723114\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46426e25f2805342174.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"42\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46426e25f2805342174-600x800.jpg\"alt=\"5bc46426e25f2805342174\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46426b52c6518078733.jpg\"data-width=\"1440\" data-height=\"1920\" data-index=\"43\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46426b52c6518078733-600x800.jpg\"alt=\"5bc46426b52c6518078733\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46425a6682398212533.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"44\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46425a6682398212533-1067x800.jpg\"alt=\"5bc46425a6682398212533\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46424bb678280527304.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"45\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46424bb678280527304-1067x800.jpg\"alt=\"5bc46424bb678280527304\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46423ccef0131736043.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"46\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46423ccef0131736043-1067x800.jpg\"alt=\"5bc46423ccef0131736043\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46422ddc4e607853227.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"47\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46422ddc4e607853227-1300x731.jpg\"alt=\"5bc46422ddc4e607853227\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46421e1b76239691266.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"48\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46421e1b76239691266-1300x731.jpg\"alt=\"5bc46421e1b76239691266\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46421a2932357046695.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"49\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc46421a2932357046695-1300x731.jpg\"alt=\"5bc46421a2932357046695\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642fc8045657111927.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"50\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642fc8045657111927-1300x731.jpg\"alt=\"5bc4642fc8045657111927\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642f78edc900750287.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"51\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642f78edc900750287-1300x731.jpg\"alt=\"5bc4642f78edc900750287\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642f2dc6b795512795.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"52\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642f2dc6b795512795-1300x731.jpg\"alt=\"5bc4642f2dc6b795512795\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642e9129b757057565.jpg\"data-width=\"1920\" data-height=\"1080\" data-index=\"53\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642e9129b757057565-1300x731.jpg\"alt=\"5bc4642e9129b757057565\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642e411ad642264944.jpg\"data-width=\"1920\" data-height=\"1440\" data-index=\"54\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642e411ad642264944-1067x800.jpg\"alt=\"5bc4642e411ad642264944\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a225563 wd-section-stretch e-flex e-con-boxed e-con e-parent\" data-id=\"a225563\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e3d1522 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"7e3d1522\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-primary wd-title-style-simple wd-title-size-custom text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title\">Talk to us!<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title set-cont-mb-s reset-last-child\">\n\t\t\t\t\t<p>Don't hesitate to contact us with any questions.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6649f45d elementor-widget elementor-widget-wd_button\" data-id=\"6649f45d\" data-element_type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-default btn-style-rectangle btn-size-default btn-color-primary btn-icon-pos-right\"  href=\"\/en\/contactos\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tContacts\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Get in touch! Please do not hesitate to contact us if you have any questions. Contacts<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-15980","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Galeria Grutas - Diamond Tours<\/title>\n<meta name=\"description\" content=\"Galeria Grutas - Diamond Tours - Fale Connosco! - N\u00e3o hesite em nos contactar para esclarecer qualquer d\u00favida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diamondtours.pt\/en\/galeria-grutas\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galeria Grutas - Diamond Tours\" \/>\n<meta property=\"og:description\" content=\"Galeria Grutas - Diamond Tours - Fale Connosco! - N\u00e3o hesite em nos contactar para esclarecer qualquer d\u00favida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diamondtours.pt\/en\/galeria-grutas\/\" \/>\n<meta property=\"og:site_name\" content=\"Diamond Tours\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T13:47:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diamondtours.pt\/galeria-grutas\/\",\"url\":\"https:\/\/diamondtours.pt\/galeria-grutas\/\",\"name\":\"Galeria Grutas - Diamond Tours\",\"isPartOf\":{\"@id\":\"https:\/\/diamondtours.pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diamondtours.pt\/galeria-grutas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diamondtours.pt\/galeria-grutas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg\",\"datePublished\":\"2024-06-25T11:33:17+00:00\",\"dateModified\":\"2024-07-02T13:47:07+00:00\",\"description\":\"Galeria Grutas - Diamond Tours - Fale Connosco! - N\u00e3o hesite em nos contactar para esclarecer qualquer d\u00favida.\",\"breadcrumb\":{\"@id\":\"https:\/\/diamondtours.pt\/galeria-grutas\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diamondtours.pt\/galeria-grutas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/diamondtours.pt\/galeria-grutas\/#primaryimage\",\"url\":\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg\",\"contentUrl\":\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diamondtours.pt\/galeria-grutas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/diamondtours.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galeria Grutas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diamondtours.pt\/#website\",\"url\":\"https:\/\/diamondtours.pt\/\",\"name\":\"Diamond Tours\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/diamondtours.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diamondtours.pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/diamondtours.pt\/#organization\",\"name\":\"Diamond Tours\",\"url\":\"https:\/\/diamondtours.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/diamondtours.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/logo_boat-removebg.png\",\"contentUrl\":\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/logo_boat-removebg.png\",\"width\":261,\"height\":191,\"caption\":\"Diamond Tours\"},\"image\":{\"@id\":\"https:\/\/diamondtours.pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galeria Grutas - Diamond Tours","description":"Galeria Grutas - Diamond Tours - Fale Connosco! - N\u00e3o hesite em nos contactar para esclarecer qualquer d\u00favida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diamondtours.pt\/en\/galeria-grutas\/","og_locale":"en_GB","og_type":"article","og_title":"Galeria Grutas - Diamond Tours","og_description":"Galeria Grutas - Diamond Tours - Fale Connosco! - N\u00e3o hesite em nos contactar para esclarecer qualquer d\u00favida.","og_url":"https:\/\/diamondtours.pt\/en\/galeria-grutas\/","og_site_name":"Diamond Tours","article_modified_time":"2024-07-02T13:47:07+00:00","og_image":[{"url":"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diamondtours.pt\/galeria-grutas\/","url":"https:\/\/diamondtours.pt\/galeria-grutas\/","name":"Galeria Grutas - Diamond Tours","isPartOf":{"@id":"https:\/\/diamondtours.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diamondtours.pt\/galeria-grutas\/#primaryimage"},"image":{"@id":"https:\/\/diamondtours.pt\/galeria-grutas\/#primaryimage"},"thumbnailUrl":"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg","datePublished":"2024-06-25T11:33:17+00:00","dateModified":"2024-07-02T13:47:07+00:00","description":"Galeria Grutas - Diamond Tours - Fale Connosco! - N\u00e3o hesite em nos contactar para esclarecer qualquer d\u00favida.","breadcrumb":{"@id":"https:\/\/diamondtours.pt\/galeria-grutas\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diamondtours.pt\/galeria-grutas\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/diamondtours.pt\/galeria-grutas\/#primaryimage","url":"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg","contentUrl":"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/5bc4642824758387571456-600x800.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/diamondtours.pt\/galeria-grutas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/diamondtours.pt\/"},{"@type":"ListItem","position":2,"name":"Galeria Grutas"}]},{"@type":"WebSite","@id":"https:\/\/diamondtours.pt\/#website","url":"https:\/\/diamondtours.pt\/","name":"Diamond Tours","description":"","publisher":{"@id":"https:\/\/diamondtours.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diamondtours.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/diamondtours.pt\/#organization","name":"Diamond Tours","url":"https:\/\/diamondtours.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/diamondtours.pt\/#\/schema\/logo\/image\/","url":"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/logo_boat-removebg.png","contentUrl":"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/logo_boat-removebg.png","width":261,"height":191,"caption":"Diamond Tours"},"image":{"@id":"https:\/\/diamondtours.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/diamondtours.pt\/en\/wp-json\/wp\/v2\/pages\/15980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamondtours.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/diamondtours.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/diamondtours.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diamondtours.pt\/en\/wp-json\/wp\/v2\/comments?post=15980"}],"version-history":[{"count":10,"href":"https:\/\/diamondtours.pt\/en\/wp-json\/wp\/v2\/pages\/15980\/revisions"}],"predecessor-version":[{"id":16065,"href":"https:\/\/diamondtours.pt\/en\/wp-json\/wp\/v2\/pages\/15980\/revisions\/16065"}],"wp:attachment":[{"href":"https:\/\/diamondtours.pt\/en\/wp-json\/wp\/v2\/media?parent=15980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}