{"id":3,"date":"2024-06-17T08:09:33","date_gmt":"2024-06-17T08:09:33","guid":{"rendered":"https:\/\/stage.diamondtours.pt\/?page_id=3"},"modified":"2025-04-23T15:26:41","modified_gmt":"2025-04-23T14:26:41","slug":"politica-privacidade","status":"publish","type":"page","link":"https:\/\/diamondtours.pt\/de\/politica-privacidade\/","title":{"rendered":"Datenschutzbestimmungen"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b327ba7 e-flex e-con-boxed e-con e-parent\" data-id=\"6b327ba7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3606ce90 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"3606ce90\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-start=\"0\" data-end=\"70\"><strong>Datenschutzbestimmungen<\/strong><br data-start=\"23\" data-end=\"26\" \/><strong>Letzte Aktualisierung: 09. September 2020<\/strong><\/h3><p class=\"\" data-start=\"72\" data-end=\"323\">Diese Datenschutzrichtlinie beschreibt unsere Richtlinien und Verfahren in Bezug auf die Erfassung, Verwendung und Offenlegung Ihrer Daten, wenn Sie den Dienst nutzen, und informiert Sie \u00fcber Ihre Datenschutzrechte und wie das Gesetz Sie sch\u00fctzt.<\/p><p class=\"\" data-start=\"325\" data-end=\"607\">Wir verwenden Ihre pers\u00f6nlichen Daten zur Bereitstellung und Verbesserung des Dienstes. Durch die Nutzung des Dienstes erkl\u00e4ren Sie sich mit der Erfassung und Nutzung von Informationen in \u00dcbereinstimmung mit dieser Datenschutzerkl\u00e4rung einverstanden. Diese Datenschutzrichtlinie wurde mit Hilfe des Datenschutzrichtlinien-Generators erstellt.<\/p><h3><strong>Auslegung und Definitionen<\/strong><br \/><strong>Auslegung<\/strong><br \/>W\u00f6rter, deren Anfangsbuchstaben gro\u00df geschrieben werden, haben unter den nachstehend beschriebenen Bedingungen eine bestimmte Bedeutung. Die folgenden Definitionen haben dieselbe Bedeutung, unabh\u00e4ngig davon, ob sie im Singular oder Plural stehen.<\/h3><p><strong>Definitionen<\/strong><br \/>F\u00fcr die Zwecke dieser Datenschutzrichtlinie:<\/p><ul><li><strong>Konto<\/strong> bedeutet ein einzigartiges Konto, das f\u00fcr Sie erstellt wurde, um auf unseren Service oder Teile davon zuzugreifen.<\/li><li><strong>Unternehmen<\/strong> (in diesem Vertrag als \"das Unternehmen\", \"wir\", \"uns\" oder \"unser\" bezeichnet) bezieht sich auf Diamond Tours, Estrada do Farol, Apartamentos Cristino Ferreira, 9\u00aa - 1\u00ba esq, 8400-505 Carvoeiro.<\/li><li><strong>Cookies<\/strong> sind kleine Dateien, die von einer Website auf Ihrem Computer, Ihrem Mobilger\u00e4t oder einem anderen Ger\u00e4t gespeichert werden und u. a. Angaben zu Ihrem Browserverlauf auf dieser Website enthalten.<\/li><li><strong>Land<\/strong> bezieht sich auf: Portugal<\/li><li><strong>Ger\u00e4t<\/strong> ist jedes Ger\u00e4t, das auf den Dienst zugreifen kann, wie z. B. ein Computer, ein Mobiltelefon oder ein digitales Tablet.<\/li><li><strong>Pers\u00f6nliche Daten<\/strong> ist jede Information, die sich auf eine identifizierte oder identifizierbare Person bezieht.<\/li><li><strong>Dienst<\/strong> bezieht sich auf die Website.<\/li><li><strong>Dienstanbieter<\/strong> bezeichnet jede nat\u00fcrliche oder juristische Person, die die Daten im Namen des Unternehmens verarbeitet. Er bezieht sich auf Drittunternehmen oder Einzelpersonen, die vom Unternehmen beauftragt wurden, den Dienst zu erleichtern, den Dienst im Namen des Unternehmens bereitzustellen, Dienstleistungen im Zusammenhang mit dem Dienst zu erbringen oder das Unternehmen bei der Analyse der Nutzung des Dienstes zu unterst\u00fctzen.<\/li><li><strong>Sozialer Netzwerkdienst eines Drittanbieters<\/strong> bezieht sich auf jede Website oder jedes soziale Netzwerk, \u00fcber die ein Nutzer sich anmelden oder ein Konto erstellen kann, um den Dienst zu nutzen.<\/li><li><strong>Verwendungsdaten<\/strong> beziehen sich auf automatisch erfasste Daten, die entweder durch die Nutzung des Dienstes oder durch die Infrastruktur des Dienstes selbst erzeugt werden (z. B. die Dauer des Besuchs einer Seite).<\/li><li><strong>Website<\/strong> verweist auf Diamond Tours - Kayak &amp; Sup, erreichbar von https:\/\/diamondtours.pt<\/li><li><strong>Sie<\/strong> bezeichnet die Person, die auf den Dienst zugreift oder ihn nutzt, bzw. das Unternehmen oder die andere juristische Person, in deren Namen diese Person auf den Dienst zugreift oder ihn nutzt.<\/li><\/ul><h3><strong>Erfassung und Verwendung Ihrer pers\u00f6nlichen Daten<\/strong><\/h3><p><strong>Arten von gesammelten Daten<\/strong><\/p><p><strong>Pers\u00f6nliche Daten<\/strong><br \/>Bei der Nutzung unseres Dienstes bitten wir Sie m\u00f6glicherweise um die Angabe bestimmter personenbezogener Daten, die dazu verwendet werden k\u00f6nnen, Sie zu kontaktieren oder zu identifizieren. Pers\u00f6nlich identifizierbare Informationen k\u00f6nnen unter anderem sein:<\/p><ul><li><p>E-Mail Adresse<\/p><\/li><li><p>Vorname und Nachname<\/p><\/li><li><p>Rufnummer<\/p><\/li><li><p>Verwendungsdaten<\/p><\/li><\/ul><p><strong>Verwendungsdaten<\/strong><br \/>Nutzungsdaten werden automatisch w\u00e4hrend der Nutzung des Dienstes erfasst.<\/p><p>Nutzungsdaten k\u00f6nnen Informationen wie die Internetprotokolladresse (z. B. IP-Adresse) Ihres Ger\u00e4ts, den Browsertyp, die Browserversion, die von Ihnen besuchten Seiten unseres Dienstes, das Datum und die Uhrzeit Ihres Besuchs, die auf diesen Seiten verbrachte Zeit, eindeutige Ger\u00e4tekennungen und andere Diagnosedaten umfassen.<\/p><p>Wenn Sie \u00fcber ein mobiles Ger\u00e4t auf den Dienst zugreifen, k\u00f6nnen wir automatisch bestimmte Informationen erfassen, einschlie\u00dflich, aber nicht beschr\u00e4nkt auf: den Typ des verwendeten mobilen Ger\u00e4ts, die eindeutige ID des mobilen Ger\u00e4ts, die IP-Adresse des mobilen Ger\u00e4ts, das mobile Betriebssystem, den Typ des verwendeten mobilen Internetbrowsers, eindeutige Ger\u00e4tekennungen und andere Diagnosedaten.<\/p><p>Wir k\u00f6nnen auch Informationen sammeln, die Ihr Browser sendet, wenn Sie unseren Dienst besuchen oder wenn Sie \u00fcber ein mobiles Ger\u00e4t auf den Dienst zugreifen.<\/p><p><strong>Tracking-Technologien und Cookies<\/strong><\/p><p>Wir verwenden Cookies und \u00e4hnliche Tracking-Technologien, um die Aktivit\u00e4ten auf Unserem Dienst zu \u00fcberwachen und bestimmte Informationen zu speichern. Zu den verwendeten Tracking-Technologien geh\u00f6ren Beacons, Tags und Skripte zum Sammeln und Verfolgen von Informationen sowie zur Verbesserung und Analyse Unseres Dienstes.<\/p><p>Sie k\u00f6nnen Ihren Browser so einstellen, dass er alle Cookies ablehnt oder anzeigt, wenn ein Cookie gesendet wird. Wenn Sie jedoch keine Cookies akzeptieren, k\u00f6nnen Sie m\u00f6glicherweise einige Teile unseres Dienstes nicht nutzen.<\/p><p>Cookies k\u00f6nnen \"persistent\" oder \"Session\" sein. Dauerhafte Cookies verbleiben auf Ihrem Computer oder Mobilger\u00e4t, auch wenn Sie offline gehen, w\u00e4hrend Sitzungscookies gel\u00f6scht werden, sobald Sie Ihren Browser schlie\u00dfen. Mehr \u00fcber Cookies erfahren Sie hier: <strong>Kekse: Wozu sind sie gut?<\/strong><\/p><p>Wir verwenden sowohl Sitzungscookies als auch dauerhafte Cookies f\u00fcr die unten beschriebenen Zwecke:<\/p><ul><li><p><strong>Notwendige \/ essentielle Cookies<\/strong><\/p><ul><li><p>Typ: Session-Cookies<\/p><\/li><li><p>Verwaltet von: Uns<\/p><\/li><li><p>Zweck: Diese Cookies sind unerl\u00e4sslich, um Ihnen die \u00fcber die Website verf\u00fcgbaren Dienste zur Verf\u00fcgung zu stellen und Ihnen die Nutzung einiger ihrer Funktionen zu erm\u00f6glichen. Sie helfen bei der Authentifizierung von Benutzern und verhindern die betr\u00fcgerische Nutzung von Konten. Ohne diese Cookies k\u00f6nnen die von Ihnen angeforderten Dienste nicht bereitgestellt werden, und wir verwenden diese Cookies nur zu diesem Zweck.<\/p><\/li><\/ul><\/li><li><p><strong>Cookie-Richtlinie \/ Hinweis zur Annahme von Cookies<\/strong><\/p><ul><li><p>Typ: Dauerhafte Cookies<\/p><\/li><li><p>Verwaltet von: Uns<\/p><\/li><li><p>Zweck: Diese Cookies zeigen an, ob die Nutzer die Verwendung von Cookies auf der Website akzeptiert haben.<\/p><\/li><\/ul><\/li><li><p><strong>Funktionalit\u00e4t Cookies<\/strong><\/p><ul><li><p>Typ: Dauerhafte Cookies<\/p><\/li><li><p>Verwaltet von: Uns<\/p><\/li><li><p>Zweck: Diese Cookies erm\u00f6glichen es uns, die von Ihnen bei der Nutzung der Website getroffenen Entscheidungen zu speichern, z. B. Ihre Anmeldedaten oder Ihre Sprachpr\u00e4ferenz. Der Zweck dieser Cookies ist es, Ihnen eine pers\u00f6nlichere Erfahrung zu bieten und zu verhindern, dass Sie Ihre Pr\u00e4ferenzen jedes Mal neu eingeben m\u00fcssen, wenn Sie die Website nutzen.<\/p><\/li><\/ul><\/li><\/ul><p>Weitere Informationen \u00fcber die von uns verwendeten Cookies und Ihre Optionen in Bezug auf sie finden Sie auf unserer <strong>Cookie-Richtlinie<\/strong> oder den Abschnitt Cookies in unserer Datenschutzrichtlinie.<\/p><h3><strong>Verwendung Ihrer pers\u00f6nlichen Daten<\/strong><\/h3><p>Das Unternehmen kann personenbezogene Daten f\u00fcr die folgenden Zwecke verwenden:<\/p><ul><li><p><strong>Zur Bereitstellung und Aufrechterhaltung unseres Dienstes<\/strong>einschlie\u00dflich der \u00dcberwachung ihrer Verwendung.<\/p><\/li><li><p><strong>So verwalten Sie Ihr Konto<\/strong>Pers\u00f6nliche Daten werden verwendet, um Ihre Registrierung als Nutzer des Dienstes zu verwalten. Die von Ihnen bereitgestellten personenbezogenen Daten k\u00f6nnen Ihnen Zugang zu verschiedenen Funktionen des Dienstes geben, die Ihnen als registriertem Nutzer zur Verf\u00fcgung stehen.<\/p><\/li><li><p><strong>F\u00fcr die Ausf\u00fchrung eines Auftrags<\/strong>die Entwicklung, Erf\u00fcllung und Durchf\u00fchrung des Vertrags \u00fcber den Kauf der von Ihnen erworbenen Produkte, Artikel oder Dienstleistungen oder eines anderen Vertrags mit uns \u00fcber den Dienst.<\/p><\/li><li><p><strong>Kontaktaufnahme mit ihm<\/strong>Sie per E-Mail, Telefonanrufe, SMS oder andere gleichwertige Formen der elektronischen Kommunikation, wie z. B. Push-Benachrichtigungen von mobilen Anwendungen, bez\u00fcglich Aktualisierungen oder informativer Mitteilungen im Zusammenhang mit vertraglich vereinbarten Funktionen, Produkten oder Diensten, einschlie\u00dflich Sicherheitsaktualisierungen, zu kontaktieren, wenn dies f\u00fcr deren Umsetzung erforderlich oder sinnvoll ist.<\/p><\/li><li><p><strong>Um Sie mit Neuigkeiten, Sonderangeboten und allgemeinen Informationen zu versorgen<\/strong> \u00fcber andere von uns angebotene Waren, Dienstleistungen und Veranstaltungen, die denen \u00e4hnlich sind, die Sie bereits gekauft oder f\u00fcr die Sie sich interessiert haben, es sei denn, Sie haben sich gegen den Erhalt dieser Art von Informationen entschieden.<\/p><\/li><li><p><strong>So verwalten Sie Ihre Bestellungen<\/strong>um Ihre Anfragen zu erf\u00fcllen und zu verwalten.<\/p><\/li><\/ul><p><strong>Wir k\u00f6nnen Ihre personenbezogenen Daten in den folgenden Situationen weitergeben<\/strong>:<\/p><ul><li><p><strong>Mit Dienstleistern<\/strong>Wir k\u00f6nnen Ihre pers\u00f6nlichen Daten an Dienstanbieter weitergeben, um die Nutzung unseres Dienstes zu \u00fcberwachen und zu analysieren oder um Sie zu kontaktieren.<\/p><\/li><li><p><strong>Bei kommerziellen \u00dcbertragungen<\/strong>Wir k\u00f6nnen Ihre pers\u00f6nlichen Daten in Verbindung mit oder w\u00e4hrend der Verhandlungen \u00fcber eine Fusion, den Verkauf von Verm\u00f6genswerten des Unternehmens, eine Finanzierung oder die \u00dcbernahme unseres gesamten oder eines Teils unseres Unternehmens durch ein anderes Unternehmen weitergeben oder \u00fcbertragen.<\/p><\/li><li><p><strong>Mit verbundenen Unternehmen<\/strong>Wir k\u00f6nnen Ihre Daten an unsere verbundenen Unternehmen weitergeben, wobei diese zur Einhaltung der vorliegenden Datenschutzrichtlinie verpflichtet sind. Zu den verbundenen Unternehmen geh\u00f6ren unsere Muttergesellschaft und alle anderen Tochtergesellschaften, Joint-Venture-Partner oder andere Unternehmen, die wir kontrollieren oder die unter gemeinsamer Kontrolle mit uns stehen.<\/p><\/li><li><p><strong>Mit Gesch\u00e4ftspartnern<\/strong>Wir k\u00f6nnen Ihre Daten an unsere Gesch\u00e4ftspartner weitergeben, um Ihnen bestimmte Produkte, Dienstleistungen oder Werbeaktionen anzubieten.<\/p><\/li><li><p><strong>Mit anderen Nutzern<\/strong>Wenn Sie pers\u00f6nliche Informationen teilen oder in \u00f6ffentlichen Bereichen mit anderen Nutzern interagieren, k\u00f6nnen diese Informationen von allen Nutzern gesehen und \u00f6ffentlich bekannt gegeben werden. Wenn Sie mit anderen Nutzern interagieren oder sich \u00fcber einen sozialen Netzwerkdienst eines Dritten registrieren, k\u00f6nnen Ihre Kontakte in diesem Netzwerk Ihren Namen, Ihr Profil, Ihre Fotos und die Beschreibung Ihrer Aktivit\u00e4ten sehen. Gleicherma\u00dfen k\u00f6nnen andere Nutzer Beschreibungen Ihrer Aktivit\u00e4ten sehen, mit Ihnen kommunizieren und Ihr Profil einsehen.<\/p><\/li><\/ul><h3><strong>Aufbewahrung Ihrer pers\u00f6nlichen Daten<\/strong><\/h3><p>Das Unternehmen wird Ihre pers\u00f6nlichen Daten nur so lange aufbewahren, wie es f\u00fcr die in dieser Datenschutzrichtlinie beschriebenen Zwecke erforderlich ist. Wir werden Ihre personenbezogenen Daten in dem Umfang aufbewahren und verwenden, der erforderlich ist, um unseren rechtlichen Verpflichtungen nachzukommen (z. B. wenn wir Ihre Daten aufbewahren m\u00fcssen, um geltende Gesetze einzuhalten), Streitigkeiten beizulegen und unsere rechtlichen Vereinbarungen und Richtlinien durchzusetzen.<\/p><p>Das Unternehmen speichert die Nutzungsdaten auch f\u00fcr interne Analysezwecke. Nutzungsdaten werden im Allgemeinen f\u00fcr einen k\u00fcrzeren Zeitraum aufbewahrt, es sei denn, sie werden verwendet, um die Sicherheit oder die Funktionalit\u00e4t unseres Dienstes zu verbessern, oder wenn wir gesetzlich verpflichtet sind, solche Daten f\u00fcr l\u00e4ngere Zeitr\u00e4ume aufzubewahren.<\/p><h3><strong>\u00dcbermittlung Ihrer pers\u00f6nlichen Daten<\/strong><\/h3><p>Ihre Informationen, einschlie\u00dflich personenbezogener Daten, werden in den Betriebsb\u00fcros des Unternehmens und an anderen Standorten verarbeitet, an denen sich die an der Verarbeitung beteiligten Parteien befinden. Das bedeutet, dass solche Informationen an Computer au\u00dferhalb Ihres Bezirks, Ihrer Provinz, Ihres Landes oder einer anderen staatlichen Gerichtsbarkeit \u00fcbertragen und dort gespeichert werden k\u00f6nnen, wo die Datenschutzgesetze von denen in Ihrer Gerichtsbarkeit abweichen k\u00f6nnen.<\/p><p>Mit Ihrer Zustimmung zu dieser Datenschutzerkl\u00e4rung und der anschlie\u00dfenden \u00dcbermittlung dieser Informationen erkl\u00e4ren Sie sich mit dieser \u00dcbertragung einverstanden.<\/p><p>Das Unternehmen ergreift alle angemessenen Ma\u00dfnahmen, um sicherzustellen, dass Ihre Daten sicher und in \u00dcbereinstimmung mit dieser Datenschutzrichtlinie behandelt werden, und es findet keine Weitergabe Ihrer pers\u00f6nlichen Daten an eine Organisation oder ein Land statt, es sei denn, es sind angemessene Kontrollen vorhanden, einschlie\u00dflich Sicherheitsma\u00dfnahmen zum Schutz Ihrer Daten und anderer pers\u00f6nlicher Informationen.<\/p><h3><strong>Offenlegung Ihrer pers\u00f6nlichen Daten<\/strong><\/h3><p><strong>Kommerzielle Transaktionen<\/strong><br \/>Wenn das Unternehmen an einer Fusion, einer \u00dcbernahme oder einem Verkauf von Verm\u00f6genswerten beteiligt ist, k\u00f6nnen Ihre pers\u00f6nlichen Daten \u00fcbertragen werden. Sie werden vor der \u00dcbertragung Ihrer pers\u00f6nlichen Daten und Ihrer Unterwerfung unter eine andere Datenschutzrichtlinie informiert.<\/p><p><strong>Einhaltung der gesetzlichen Bestimmungen<\/strong><br \/>Unter bestimmten Umst\u00e4nden kann das Unternehmen verpflichtet sein, Ihre pers\u00f6nlichen Daten offenzulegen, wenn dies gesetzlich vorgeschrieben ist oder als Reaktion auf berechtigte Anfragen von Beh\u00f6rden (z. B. einem Gericht oder einer staatlichen Stelle).<\/p><p><strong>Sonstige rechtliche Anforderungen<\/strong><br \/>Das Unternehmen kann Ihre pers\u00f6nlichen Daten offenlegen, wenn es in gutem Glauben davon ausgeht, dass eine solche Offenlegung notwendig ist, um:<\/p><ul><li><p>Zur Erf\u00fcllung einer gesetzlichen Verpflichtung<\/p><\/li><li><p>Schutz und Verteidigung der Rechte und des Eigentums des Unternehmens<\/p><\/li><li><p>Verhinderung oder Untersuchung m\u00f6glicher Unregelm\u00e4\u00dfigkeiten im Zusammenhang mit dem Dienst<\/p><\/li><li><p>die pers\u00f6nliche Sicherheit der Nutzer des Dienstes oder der \u00d6ffentlichkeit zu sch\u00fctzen<\/p><\/li><li><p>Schutz vor rechtlichen Verpflichtungen<\/p><\/li><\/ul><p><strong>Sicherheit Ihrer pers\u00f6nlichen Daten<\/strong><br \/>Die Sicherheit Ihrer pers\u00f6nlichen Daten ist uns wichtig, aber bitte denken Sie daran, dass keine Methode der \u00dcbertragung \u00fcber das Internet oder der elektronischen Speicherung 100% sicher ist. Obwohl wir uns bem\u00fchen, kommerziell akzeptable Mittel zum Schutz Ihrer pers\u00f6nlichen Daten zu verwenden, k\u00f6nnen wir deren absolute Sicherheit nicht garantieren.<\/p><h3><strong>Ihre Datenschutzrechte in Kalifornien<\/strong><br \/>(<strong>Kaliforniens \"Shine the Light\"-Gesetz<\/strong>)<\/h3><p>Gem\u00e4\u00df California Civil Code Section 1798 (bekannt als \"Shine the Light\"-Gesetz) k\u00f6nnen in Kalifornien ans\u00e4ssige Personen, die eine Gesch\u00e4ftsbeziehung mit uns unterhalten, einmal j\u00e4hrlich Informationen \u00fcber die Weitergabe ihrer pers\u00f6nlichen Daten an Dritte f\u00fcr deren Direktmarketingzwecke anfordern.<\/p><p>Wenn Sie weitere Informationen im Rahmen dieses Gesetzes anfordern m\u00f6chten und in Kalifornien ans\u00e4ssig sind, k\u00f6nnen Sie sich \u00fcber die nachstehenden Kontaktinformationen an uns wenden.<\/p><h3><strong>Datenschutzrechte f\u00fcr minderj\u00e4hrige Nutzer in Kalifornien<\/strong><br \/>(<strong>Abschnitt 22581 des California Business and Professions Code<\/strong>)<\/h3><p>Abschnitt 22581 des California Business and Professions Code erlaubt es kalifornischen Einwohnern unter 18 Jahren, die registrierte Nutzer von Websites, Diensten oder Online-Anwendungen sind, die Entfernung von Inhalten oder Informationen zu verlangen, die sie \u00f6ffentlich ver\u00f6ffentlicht haben.<\/p><p>Wenn Sie in Kalifornien ans\u00e4ssig sind und die L\u00f6schung dieser Daten beantragen m\u00f6chten, k\u00f6nnen Sie uns \u00fcber die unten angegebenen Kontaktdaten kontaktieren, einschlie\u00dflich der Ihrem Konto zugeordneten E-Mail-Adresse.<\/p><p>Bitte beachten Sie, dass Ihre Anfrage <strong>garantiert nicht<\/strong> die totale oder vollst\u00e4ndige Entfernung von online ver\u00f6ffentlichten Inhalten oder Informationen, und dass die Gesetzgebung <strong>nicht erlauben oder verlangen<\/strong> Entfernung unter bestimmten Umst\u00e4nden.<\/p><h3><strong>Links zu anderen Websites<\/strong><\/h3><p>Unser Service kann Links zu anderen Websites enthalten, die nicht von uns betrieben werden. Wenn Sie auf einen Link einer dritten Partei klicken, werden Sie auf die Website dieser dritten Partei weitergeleitet. Wir empfehlen Ihnen dringend, die Datenschutzrichtlinien jeder Website, die Sie besuchen, zu lesen.<\/p><p>Wir haben keine Kontrolle \u00fcber den Inhalt, die Datenschutzrichtlinien oder die Praktiken von Websites oder Diensten Dritter und \u00fcbernehmen keine Verantwortung f\u00fcr diese.<\/p><h3><strong>\u00c4nderungen an dieser Datenschutzrichtlinie<\/strong><\/h3><p>Wir k\u00f6nnen unsere Datenschutzrichtlinie von Zeit zu Zeit aktualisieren. Wir werden Sie \u00fcber alle \u00c4nderungen informieren, indem wir die neue Datenschutzrichtlinie auf dieser Seite ver\u00f6ffentlichen.<\/p><p>Wir werden Sie per E-Mail und\/oder \u00fcber einen auff\u00e4lligen Hinweis in unserem Service informieren, bevor die \u00c4nderung in Kraft tritt, und das Datum der letzten Aktualisierung\" oben in dieser Datenschutzrichtlinie aktualisieren.<\/p><p>Wir empfehlen Ihnen, diese Datenschutzrichtlinie regelm\u00e4\u00dfig auf \u00c4nderungen zu \u00fcberpr\u00fcfen. \u00c4nderungen an dieser Datenschutzrichtlinie werden wirksam, sobald sie auf dieser Seite ver\u00f6ffentlicht werden.<\/p><h3 data-start=\"0\" data-end=\"18\"><strong data-start=\"0\" data-end=\"16\">Kontakt<\/strong><\/h3><p class=\"\" data-start=\"20\" data-end=\"100\">Wenn Sie Fragen zu dieser Datenschutzrichtlinie haben, k\u00f6nnen Sie sich an uns wenden:<\/p><ul data-start=\"101\" data-end=\"137\"><li class=\"\" data-start=\"101\" data-end=\"137\"><p class=\"\" data-start=\"103\" data-end=\"137\">Per E-Mail: <a href=\"mailto:geral@diamondtours.pt\" rel=\"noopener\" data-start=\"114\" data-end=\"135\">geral@diamondtours.pt<\/a><\/p><\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p data-start=\"325\" data-end=\"607\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidade\u00daltima atualiza\u00e7\u00e3o: 09 de setembro de 2020 Esta Pol\u00edtica de Privacidade descreve as nossas pol\u00edticas e procedimentos relativamente<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de Privacidade - Diamond Tours<\/title>\n<meta name=\"description\" content=\"A sua privacidade \u00e9 importante para n\u00f3s. Esta Pol\u00edtica de Privacidade e Cookies explica como recolhemos, utilizamos, divulgamos e protegemos as suas informa\u00e7\u00f5es pessoais, bem como o uso de cookies no nosso site.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diamondtours.pt\/de\/politica-privacidade\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidade - Diamond Tours\" \/>\n<meta property=\"og:description\" content=\"A sua privacidade \u00e9 importante para n\u00f3s. Esta Pol\u00edtica de Privacidade e Cookies explica como recolhemos, utilizamos, divulgamos e protegemos as suas informa\u00e7\u00f5es pessoais, bem como o uso de cookies no nosso site.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diamondtours.pt\/de\/politica-privacidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Diamond Tours\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T14:26:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diamondtours.pt\/politica-privacidade\/\",\"url\":\"https:\/\/diamondtours.pt\/politica-privacidade\/\",\"name\":\"Pol\u00edtica de Privacidade - Diamond Tours\",\"isPartOf\":{\"@id\":\"https:\/\/diamondtours.pt\/#website\"},\"datePublished\":\"2024-06-17T08:09:33+00:00\",\"dateModified\":\"2025-04-23T14:26:41+00:00\",\"description\":\"A sua privacidade \u00e9 importante para n\u00f3s. Esta Pol\u00edtica de Privacidade e Cookies explica como recolhemos, utilizamos, divulgamos e protegemos as suas informa\u00e7\u00f5es pessoais, bem como o uso de cookies no nosso site.\",\"breadcrumb\":{\"@id\":\"https:\/\/diamondtours.pt\/politica-privacidade\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diamondtours.pt\/politica-privacidade\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diamondtours.pt\/politica-privacidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/diamondtours.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diamondtours.pt\/#website\",\"url\":\"https:\/\/diamondtours.pt\/\",\"name\":\"Diamond Tours\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/diamondtours.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diamondtours.pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/diamondtours.pt\/#organization\",\"name\":\"Diamond Tours\",\"url\":\"https:\/\/diamondtours.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/diamondtours.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/logo_boat-removebg.png\",\"contentUrl\":\"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/logo_boat-removebg.png\",\"width\":261,\"height\":191,\"caption\":\"Diamond Tours\"},\"image\":{\"@id\":\"https:\/\/diamondtours.pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidade - Diamond Tours","description":"A sua privacidade \u00e9 importante para n\u00f3s. Esta Pol\u00edtica de Privacidade e Cookies explica como recolhemos, utilizamos, divulgamos e protegemos as suas informa\u00e7\u00f5es pessoais, bem como o uso de cookies no nosso site.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diamondtours.pt\/de\/politica-privacidade\/","og_locale":"de_DE","og_type":"article","og_title":"Pol\u00edtica de Privacidade - Diamond Tours","og_description":"A sua privacidade \u00e9 importante para n\u00f3s. Esta Pol\u00edtica de Privacidade e Cookies explica como recolhemos, utilizamos, divulgamos e protegemos as suas informa\u00e7\u00f5es pessoais, bem como o uso de cookies no nosso site.","og_url":"https:\/\/diamondtours.pt\/de\/politica-privacidade\/","og_site_name":"Diamond Tours","article_modified_time":"2025-04-23T14:26:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diamondtours.pt\/politica-privacidade\/","url":"https:\/\/diamondtours.pt\/politica-privacidade\/","name":"Pol\u00edtica de Privacidade - Diamond Tours","isPartOf":{"@id":"https:\/\/diamondtours.pt\/#website"},"datePublished":"2024-06-17T08:09:33+00:00","dateModified":"2025-04-23T14:26:41+00:00","description":"A sua privacidade \u00e9 importante para n\u00f3s. Esta Pol\u00edtica de Privacidade e Cookies explica como recolhemos, utilizamos, divulgamos e protegemos as suas informa\u00e7\u00f5es pessoais, bem como o uso de cookies no nosso site.","breadcrumb":{"@id":"https:\/\/diamondtours.pt\/politica-privacidade\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diamondtours.pt\/politica-privacidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/diamondtours.pt\/politica-privacidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/diamondtours.pt\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidade"}]},{"@type":"WebSite","@id":"https:\/\/diamondtours.pt\/#website","url":"https:\/\/diamondtours.pt\/","name":"Diamant-Touren","description":"","publisher":{"@id":"https:\/\/diamondtours.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diamondtours.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/diamondtours.pt\/#organization","name":"Diamant-Touren","url":"https:\/\/diamondtours.pt\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diamondtours.pt\/#\/schema\/logo\/image\/","url":"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/logo_boat-removebg.png","contentUrl":"https:\/\/diamondtours.pt\/wp-content\/uploads\/2024\/06\/logo_boat-removebg.png","width":261,"height":191,"caption":"Diamond Tours"},"image":{"@id":"https:\/\/diamondtours.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/diamondtours.pt\/de\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamondtours.pt\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/diamondtours.pt\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/diamondtours.pt\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diamondtours.pt\/de\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":13,"href":"https:\/\/diamondtours.pt\/de\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":16315,"href":"https:\/\/diamondtours.pt\/de\/wp-json\/wp\/v2\/pages\/3\/revisions\/16315"}],"wp:attachment":[{"href":"https:\/\/diamondtours.pt\/de\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}